{"id":79,"date":"2020-09-18T05:11:15","date_gmt":"2020-09-18T05:11:15","guid":{"rendered":"http:\/\/ilgusolution.onedoc.ph\/?page_id=79"},"modified":"2021-02-19T02:20:15","modified_gmt":"2021-02-19T02:20:15","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/ilgusolution.onedoc.ph\/index.php\/contact-us\/","title":{"rendered":"Contact Us"},"content":{"rendered":"\n<div class=\"wp-container-1 wp-block-group\"><div class=\"wp-block-group__inner-container\"><noscript class=\"ninja-forms-noscript-message\">\n    Notice: JavaScript is required for this content.<\/noscript><div id=\"nf-form-3-cont\" class=\"nf-form-cont\" aria-live=\"polite\" aria-labelledby=\"nf-form-title-3\" aria-describedby=\"nf-form-errors-3\" role=\"form\">\n\n    <div class=\"nf-loading-spinner\"><\/div>\n\n<\/div>\n        <!-- TODO: Move to Template File. -->\n        <script>var formDisplay=1;var nfForms=nfForms||[];var form=[];form.id='3';form.settings={\"objectType\":\"Form Setting\",\"editActive\":\"1\",\"title\":\"Enquiry\",\"created_at\":\"2021-02-19 10:06:48\",\"form_title\":\"Enquiry\",\"default_label_pos\":\"above\",\"show_title\":\"0\",\"clear_complete\":\"1\",\"hide_complete\":\"1\",\"logged_in\":\"0\",\"wrapper_class\":\"\",\"element_class\":\"\",\"key\":\"\",\"add_submit\":\"1\",\"currency\":\"\",\"unique_field_error\":\"A form with this value has already been submitted.\",\"not_logged_in_msg\":\"\",\"sub_limit_msg\":\"The form has reached its submission limit.\",\"calculations\":[],\"formContentData\":[\"firstname_1523908368154\",\"lastname_1523908369534\",\"email_1523908522614\",\"phone_1523908588264\",\"message_1613700464020\",\"submit_1523908548082\"],\"drawerDisabled\":\"\",\"allow_public_link\":0,\"embed_form\":\"\",\"repeatable_fieldsets\":\"\",\"ninjaForms\":\"Ninja Forms\",\"changeEmailErrorMsg\":\"Please enter a valid email address!\",\"changeDateErrorMsg\":\"Please enter a valid date!\",\"confirmFieldErrorMsg\":\"These fields must match!\",\"fieldNumberNumMinError\":\"Number Min Error\",\"fieldNumberNumMaxError\":\"Number Max Error\",\"fieldNumberIncrementBy\":\"Please increment by \",\"fieldTextareaRTEInsertLink\":\"Insert Link\",\"fieldTextareaRTEInsertMedia\":\"Insert Media\",\"fieldTextareaRTESelectAFile\":\"Select a file\",\"formErrorsCorrectErrors\":\"Please correct errors before submitting this form.\",\"formHoneypot\":\"If you are a human seeing this field, please leave it empty.\",\"validateRequiredField\":\"This is a required field.\",\"honeypotHoneypotError\":\"Honeypot Error\",\"fileUploadOldCodeFileUploadInProgress\":\"File Upload in Progress.\",\"fileUploadOldCodeFileUpload\":\"FILE UPLOAD\",\"currencySymbol\":\"&#8369;\",\"fieldsMarkedRequired\":\"Fields marked with an <span class=\\\"ninja-forms-req-symbol\\\">*<\\\/span> are required\",\"thousands_sep\":\",\",\"decimal_point\":\".\",\"siteLocale\":\"en_US\",\"dateFormat\":\"m\\\/d\\\/Y\",\"startOfWeek\":\"1\",\"of\":\"of\",\"previousMonth\":\"Previous Month\",\"nextMonth\":\"Next Month\",\"months\":[\"January\",\"February\",\"March\",\"April\",\"May\",\"June\",\"July\",\"August\",\"September\",\"October\",\"November\",\"December\"],\"monthsShort\":[\"Jan\",\"Feb\",\"Mar\",\"Apr\",\"May\",\"Jun\",\"Jul\",\"Aug\",\"Sep\",\"Oct\",\"Nov\",\"Dec\"],\"weekdays\":[\"Sunday\",\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\"],\"weekdaysShort\":[\"Sun\",\"Mon\",\"Tue\",\"Wed\",\"Thu\",\"Fri\",\"Sat\"],\"weekdaysMin\":[\"Su\",\"Mo\",\"Tu\",\"We\",\"Th\",\"Fr\",\"Sa\"],\"currency_symbol\":\"\",\"beforeForm\":\"\",\"beforeFields\":\"\",\"afterFields\":\"\",\"afterForm\":\"\"};form.fields=[{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":1,\"idAttribute\":\"id\",\"label\":\"First Name\",\"type\":\"firstname\",\"key\":\"firstname_1523908368154\",\"label_pos\":\"above\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"one-half first\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"custom_name_attribute\":\"fname\",\"field_label\":\"First Name\",\"field_key\":\"firstname_1523908368154\",\"personally_identifiable\":1,\"value\":\"\",\"id\":9,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"firstname\",\"element_templates\":[\"firstname\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":2,\"idAttribute\":\"id\",\"label\":\"Last Name\",\"type\":\"lastname\",\"key\":\"lastname_1523908369534\",\"label_pos\":\"above\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"one-half second\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"custom_name_attribute\":\"lname\",\"drawerDisabled\":\"\",\"field_label\":\"Last Name\",\"field_key\":\"lastname_1523908369534\",\"personally_identifiable\":1,\"value\":\"\",\"id\":10,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"lastname\",\"element_templates\":[\"lastname\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":3,\"idAttribute\":\"id\",\"label\":\"Email\",\"type\":\"email\",\"key\":\"email_1523908522614\",\"label_pos\":\"above\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"custom_name_attribute\":\"email\",\"field_label\":\"Email\",\"field_key\":\"email_1523908522614\",\"personally_identifiable\":1,\"value\":\"\",\"drawerDisabled\":false,\"id\":11,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"email\",\"element_templates\":[\"email\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":4,\"idAttribute\":\"id\",\"label\":\"Phone\",\"type\":\"phone\",\"key\":\"phone_1523908588264\",\"label_pos\":\"above\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Character(s) left\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"mask\":\"\",\"custom_mask\":\"\",\"custom_name_attribute\":\"phone\",\"field_label\":\"Phone\",\"field_key\":\"phone_1523908588264\",\"personally_identifiable\":1,\"value\":\"\",\"drawerDisabled\":false,\"id\":12,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"textbox\",\"element_templates\":[\"tel\",\"textbox\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":7,\"idAttribute\":\"id\",\"label\":\"Message\",\"type\":\"textarea\",\"key\":\"message_1613700464020\",\"label_pos\":\"above\",\"required\":1,\"default\":\"\",\"placeholder\":\"\",\"container_class\":\"\",\"element_class\":\"\",\"input_limit\":\"\",\"input_limit_type\":\"characters\",\"input_limit_msg\":\"Character(s) left\",\"manual_key\":\"\",\"admin_label\":\"\",\"help_text\":\"\",\"textarea_rte\":\"\",\"disable_rte_mobile\":\"\",\"textarea_media\":\"\",\"field_label\":\"Details\",\"field_key\":\"details_1523908537286\",\"value\":\"\",\"drawerDisabled\":false,\"id\":15,\"beforeField\":\"\",\"afterField\":\"\",\"parentType\":\"textarea\",\"element_templates\":[\"textarea\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap\"},{\"objectType\":\"Field\",\"objectDomain\":\"fields\",\"editActive\":false,\"order\":10,\"idAttribute\":\"id\",\"type\":\"submit\",\"label\":\"Submit\",\"processing_label\":\"Processing\",\"container_class\":\"\",\"element_class\":\"\",\"key\":\"submit_1523908548082\",\"field_label\":\"Submit\",\"field_key\":\"submit_1523908548082\",\"id\":18,\"beforeField\":\"\",\"afterField\":\"\",\"value\":\"\",\"label_pos\":\"above\",\"parentType\":\"textbox\",\"element_templates\":[\"submit\",\"button\",\"input\"],\"old_classname\":\"\",\"wrap_template\":\"wrap-no-label\"}];nfForms.push(form);<\/script>\n        <\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile has-black-color has-pale-cyan-blue-background-color has-text-color has-background\" style=\"grid-template-columns:15% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" width=\"1024\" height=\"1024\" src=\"https:\/\/ilgusolution.onedoc.ph\/wp-content\/uploads\/2020\/09\/Contact-Icon-3-1024x1024.png\" alt=\"\" class=\"wp-image-586\" srcset=\"https:\/\/ilgusolution.onedoc.ph\/wp-content\/uploads\/2020\/09\/Contact-Icon-3-1024x1024.png 1024w, https:\/\/ilgusolution.onedoc.ph\/wp-content\/uploads\/2020\/09\/Contact-Icon-3-300x300.png 300w, https:\/\/ilgusolution.onedoc.ph\/wp-content\/uploads\/2020\/09\/Contact-Icon-3-150x150.png 150w, https:\/\/ilgusolution.onedoc.ph\/wp-content\/uploads\/2020\/09\/Contact-Icon-3-768x768.png 768w, https:\/\/ilgusolution.onedoc.ph\/wp-content\/uploads\/2020\/09\/Contact-Icon-3-1536x1536.png 1536w, https:\/\/ilgusolution.onedoc.ph\/wp-content\/uploads\/2020\/09\/Contact-Icon-3.png 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<pre id=\"block-9f3540ba-419f-4cf5-ac26-c3fc7b57f7d2\" class=\"wp-block-preformatted\"><strong>Mobile :  (0917) 821-0319\n          (0995) 298-7956\n          (0917) 518-4055\n          (0945) 978-3891\nLandline: (+632) 8441-1091 and (+632) 8277-6704\nEmail : <a href=\"mailto:ilgusolution@onedoc.ph\" target=\"_blank\" rel=\"noreferrer noopener\">ilgusolution@onedoc.ph<\/a><\/strong><\/pre>\n<\/div><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mobile : (0917) 821-0319 (0995) 298-7956 (0917) 518-4055 (0945) 978-3891 Landline: (+632) 8441-1091 and (+632) 8277-6704 Email : ilgusolution@onedoc.ph<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/ilgusolution.onedoc.ph\/index.php\/wp-json\/wp\/v2\/pages\/79"}],"collection":[{"href":"https:\/\/ilgusolution.onedoc.ph\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ilgusolution.onedoc.ph\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ilgusolution.onedoc.ph\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ilgusolution.onedoc.ph\/index.php\/wp-json\/wp\/v2\/comments?post=79"}],"version-history":[{"count":47,"href":"https:\/\/ilgusolution.onedoc.ph\/index.php\/wp-json\/wp\/v2\/pages\/79\/revisions"}],"predecessor-version":[{"id":1023,"href":"https:\/\/ilgusolution.onedoc.ph\/index.php\/wp-json\/wp\/v2\/pages\/79\/revisions\/1023"}],"wp:attachment":[{"href":"https:\/\/ilgusolution.onedoc.ph\/index.php\/wp-json\/wp\/v2\/media?parent=79"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}